{"id":684,"date":"2019-02-01T17:11:27","date_gmt":"2019-02-01T22:11:27","guid":{"rendered":"http:\/\/crcoc.ca\/?page_id=684"},"modified":"2026-05-11T11:40:32","modified_gmt":"2026-05-11T15:40:32","slug":"adultes","status":"publish","type":"page","link":"https:\/\/www.crcoc.ca\/fr\/adultes\/","title":{"rendered":"Adultes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"684\" class=\"elementor elementor-684 elementor-656\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb25be5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb25be5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24ff3cb\" data-id=\"24ff3cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecfe06e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ecfe06e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0146819 elementor-widget elementor-widget-image\" data-id=\"0146819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-27621\" alt=\"\" srcset=\"https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-e1695998152500.png 150w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-300x300.png 300w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-1024x1024.png 1024w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-768x768.png 768w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36931fb elementor-widget elementor-widget-text-editor\" data-id=\"36931fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>ADULTES<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad0ea73 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ad0ea73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f397375 elementor-widget elementor-widget-image\" data-id=\"f397375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"300\" src=\"https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/221212_Adult_CoverPhoto-1.png\" class=\"attachment-full size-full wp-image-27664\" alt=\"\" srcset=\"https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/221212_Adult_CoverPhoto-1.png 900w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/221212_Adult_CoverPhoto-1-300x100.png 300w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/221212_Adult_CoverPhoto-1-768x256.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5845418 elementor-widget elementor-widget-heading\" data-id=\"5845418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROGRAMME D'ACCUEIL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99ea272 elementor-widget elementor-widget-text-editor\" data-id=\"99ea272\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Parlez-nous de votre visite<\/span><\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b14f44 elementor-widget elementor-widget-text-editor\" data-id=\"0b14f44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"cvGsUA direction-ltr align-center para-style-body\"><strong><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Votre opinion compte. En cinq minutes, dites-nous comment on peut mieux r\u00e9pondre \u00e0 vos besoins.<\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-311ef31 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"311ef31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/survey.crg.ca\/index.php\/?r=survey\/index&#038;newtest=Y&#038;sid=327839&#038;lang=en&#038;list=13&#038;OrgID=2ILuSys1&#038;ProgID=499\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cliquez ici<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4781ca elementor-widget elementor-widget-text-editor\" data-id=\"b4781ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"cvGsUA direction-ltr align-center para-style-body\"><strong><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Aucune donn\u00e9e ne servira \u00e0 vous identifier.<br \/><\/span><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Merci<\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1536c12 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1536c12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-146fbd3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"146fbd3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a7d71b\" data-id=\"8a7d71b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-abd691f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abd691f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ab61c4e\" data-id=\"ab61c4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f4fc59 elementor-widget elementor-widget-heading\" data-id=\"1f4fc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Le CRCOC est un endroit chaleureux qui accueille toute personne qui recherche du soutien et des ressources ou qui est confront\u00e9e \u00e0 une crise<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a74c501 elementor-widget elementor-widget-text-editor\" data-id=\"a74c501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>LES SERVICES ET LE SOUTIEN QUE NOUS OFFRONS :<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83d31d3 elementor-widget elementor-widget-text-editor\" data-id=\"83d31d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Nos intervenant.e.s \u00e0 l&rsquo;accueil offre les services et le soutien suivant aux personnes \u00e2g\u00e9s de plus de 18 ans :<\/h3><ul><li><h3>Un environnement ouvert et sans jugement pour discuter de votre situation et de vos besoins ;<\/h3><\/li><li><h3><span data-slate-object=\"text\" data-key=\"768\" data-slate-fragment=\"JTdCJTIyb2JqZWN0JTIyJTNBJTIyZG9jdW1lbnQlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJibG9jayUyMiUyQyUyMnR5cGUlMjIlM0ElMjJ6b25lJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiU3RCUyQyUyMm5vZGVzJTIyJTNBJTVCJTdCJTIyb2JqZWN0JTIyJTNBJTIyYmxvY2slMjIlMkMlMjJ0eXBlJTIyJTNBJTIybGlnbmUlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJibG9jayUyMiUyQyUyMnR5cGUlMjIlM0ElMjJkZWZhdWx0LWVsZW1lbnQlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJ0ZXh0JTIyJTJDJTIydGV4dCUyMiUzQSUyMkZhaXJlJTIwdW5lJTIwJUMzJUE5dmFsdWF0aW9uJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlNUQlN0QlMkMlN0IlMjJvYmplY3QlMjIlM0ElMjJ0ZXh0JTIyJTJDJTIydGV4dCUyMiUzQSUyMiU1Q24lMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU3QiUyMm9iamVjdCUyMiUzQSUyMm1hcmslMjIlMkMlMjJ0eXBlJTIyJTNBJTIyc3R5bGUlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTIyc3R5bGUlMjIlM0ElMjJGb250R3Jpc05vcm1hbGlzYXklMjIlN0QlN0QlNUQlN0QlMkMlN0IlMjJvYmplY3QlMjIlM0ElMjJ0ZXh0JTIyJTJDJTIydGV4dCUyMiUzQSUyMk9mZnJpciUyMHVuJTIwY29uc2VpbCUyMCVDMyVBMCUyMGNvdXJ0JTIwdGVybWUlMjAoNCUyMCVDMyVBMCUyMCUyMiUyQyUyMm1hcmtzJTIyJTNBJTVCJTVEJTdEJTJDJTdCJTIyb2JqZWN0JTIyJTNBJTIydGV4dCUyMiUyQyUyMnRleHQlMjIlM0ElMjI2JTIyJTJDJTIybWFya3MlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJtYXJrJTIyJTJDJTIydHlwZSUyMiUzQSUyMmNsYXNzTmFtZSUyMiUyQyUyMmRhdGElMjIlM0ElN0IlMjJjbGFzc05hbWUlMjIlM0ElMjJpZF81Nzc3NjNlNS1kNDE1LTRlZGMtODE3Yy1lYTA4YTlkNTQ0ZDItNTYlMjIlN0QlN0QlMkMlN0IlMjJvYmplY3QlMjIlM0ElMjJtYXJrJTIyJTJDJTIydHlwZSUyMiUzQSUyMnN0eWxlJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnN0eWxlJTIyJTNBJTIyVHJhaXRWZXJ0JTIyJTdEJTdEJTVEJTdEJTJDJTdCJTIyb2JqZWN0JTIyJTNBJTIydGV4dCUyMiUyQyUyMnRleHQlMjIlM0ElMjIlQzIlQTBzJUMzJUE5YW5jZXMpJTIwcG91ciUyMGxlcyUyMHBlcnNvbm5lcyUyMGRlJTIwcGx1cyUyMGRlJTIwJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlNUQlN0QlMkMlN0IlMjJvYmplY3QlMjIlM0ElMjJ0ZXh0JTIyJTJDJTIydGV4dCUyMiUzQSUyMjE4JTIyJTJDJTIybWFya3MlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJtYXJrJTIyJTJDJTIydHlwZSUyMiUzQSUyMmNsYXNzTmFtZSUyMiUyQyUyMmRhdGElMjIlM0ElN0IlMjJjbGFzc05hbWUlMjIlM0ElMjJpZF81Nzc3NjNlNS1kNDE1LTRlZGMtODE3Yy1lYTA4YTlkNTQ0ZDItNTklMjIlN0QlN0QlMkMlN0IlMjJvYmplY3QlMjIlM0ElMjJtYXJrJTIyJTJDJTIydHlwZSUyMiUzQSUyMnN0eWxlJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnN0eWxlJTIyJTNBJTIyVHJhaXRWZXJ0JTIyJTdEJTdEJTVEJTdEJTJDJTdCJTIyb2JqZWN0JTIyJTNBJTIydGV4dCUyMiUyQyUyMnRleHQlMjIlM0ElMjIlQzIlQTBhbnMuJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlNUQlN0QlMkMlN0IlMjJvYmplY3QlMjIlM0ElMjJ0ZXh0JTIyJTJDJTIydGV4dCUyMiUzQSUyMiU1Q24lMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU3QiUyMm9iamVjdCUyMiUzQSUyMm1hcmslMjIlMkMlMjJ0eXBlJTIyJTNBJTIyc3R5bGUlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTIyc3R5bGUlMjIlM0ElMjJDYXJTZXBhcmF0ZXVyJTIyJTdEJTdEJTVEJTdEJTJDJTdCJTIyb2JqZWN0JTIyJTNBJTIydGV4dCUyMiUyQyUyMnRleHQlMjIlM0ElMjJPcmllbnRlciUyMGxlcyUyMHBlcnNvbm5lcyUyMHZlcnMlMjBkZXMlMjBwYXJ0ZW5haXJlcyUyMGNvbW11bmF1dGFpcmVzJTIwc2klMjBuJUMzJUE5Y2Vzc2FpcmUlMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU1RCU3RCU1RCU3RCU1RCU3RCU1RCU3RCU1RCU3RA==\">Des r\u00e9f\u00e9rences vers des partenaires communautaires en fonction de vos besoins ;<\/span><\/h3><\/li><li><h3>Si vous \u00eates \u00e0 la recherche de services de counseling, veuillez consulter la <a href=\"https:\/\/www.crcoc.ca\/fr\/adultes\/ressources-pour-adultes\/\">liste des ressources communautaires<\/a>.<\/h3><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7882dcf elementor-widget elementor-widget-text-editor\" data-id=\"7882dcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Nos intervenant.e.s \u00e0 l&rsquo;accueil sont l\u00e0 pour vous.\u00a0 Iels sont disponibles pour vous parler du lundi au vendredi de 8 h30 \u00e0 midi et 13 h \u00e0 16 h 30.\u00a0 Nous vous encourageons \u00e0 prendre rendez-vous en appelant au (613) 830-4357.<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdc121d elementor-widget elementor-widget-heading\" data-id=\"cdc121d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VOUS TRAVERSEZ UNE CRISE FINANCI\u00c8RE ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-90faf04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90faf04\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9012cbc\" data-id=\"9012cbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4594cef elementor-widget elementor-widget-text-editor\" data-id=\"4594cef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78cf05c elementor-widget elementor-widget-heading\" data-id=\"78cf05c\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><h2>\u00a0<\/h2><h2><strong>Besoin d&rsquo;aide pour vos factures d&rsquo;\u00e9nergie ?<\/strong><\/h2><h3 class=\"elementor-heading-title elementor-size-default\">Le Centre de ressources communautaires Orl\u00e9ans-Cumberland (CRCOC) peut vous aider \u00e0 acc\u00e9der \u00e0 des programmes qui peuvent vous aider financi\u00e8rement, tel que :<\/h3><\/div><\/div><div class=\"elementor-element elementor-element-189e810 elementor-widget elementor-widget-text-editor\" data-id=\"189e810\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-text-editor elementor-clearfix\"><div class=\"wpb_text_column wpb_content_element \"><div class=\"wpb_wrapper\"><ul><li><h3><strong><a href=\"https:\/\/www.oeb.ca\/fr\/tarifs-et-votre-facture\/aide-pour-les-consommateurs-faible-revenu\/programme-ontarien-daide-relative\">Programme ontarien d\u2019aide relative aux frais d\u2019\u00e9lectricit\u00e9<\/a><\/strong>\u00a0: Cr\u00e9dit mensuel possible sur facture d\u2019\u00e9lectricit\u00e9 pour consommateurs \u00e0 faible revenu <b>(clients Enbridge et Hydro One)<\/b>.<\/h3><\/li><li><h3><strong><a href=\"https:\/\/www.oeb.ca\/fr\/tarifs-et-votre-facture\/aide-pour-les-consommateurs-faible-revenu\/programme-daide-aux-impayes\">Programme d\u2019aide aux impay\u00e9s d\u2019\u00e9nergie<\/a>\u00a0(AIE)<\/strong> : Un rabais mensuel de Hydro One sur votre facture peut \u00eatre disponible pour les consommateurs \u00e0 faible revenu.<\/h3><\/li><li><h3>Pour en savoir plus ou v\u00e9rifier votre admissibilit\u00e9, contactez-nous au (613) 830-4357<\/h3><\/li><\/ul><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-94fc63f\" data-id=\"94fc63f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b017dfa elementor-widget elementor-widget-image\" data-id=\"b017dfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/www.crcoc.ca\/wp-content\/uploads\/2025\/05\/Energy-Bill-Assistance-Program-FR-791x1024.jpg\" class=\"attachment-large size-large wp-image-35219\" alt=\"\" srcset=\"https:\/\/www.crcoc.ca\/wp-content\/uploads\/2025\/05\/Energy-Bill-Assistance-Program-FR-791x1024.jpg 791w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2025\/05\/Energy-Bill-Assistance-Program-FR-232x300.jpg 232w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2025\/05\/Energy-Bill-Assistance-Program-FR-768x994.jpg 768w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2025\/05\/Energy-Bill-Assistance-Program-FR-1187x1536.jpg 1187w, https:\/\/www.crcoc.ca\/wp-content\/uploads\/2025\/05\/Energy-Bill-Assistance-Program-FR.jpg 1545w\" sizes=\"(max-width: 791px) 100vw, 791px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41be167 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41be167\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cf96a05\" data-id=\"cf96a05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4787893 elementor-widget elementor-widget-heading\" data-id=\"4787893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTACTEZ-NOUS !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-505a35e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"505a35e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6fc5125\" data-id=\"6fc5125\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b3229c elementor-widget elementor-widget-heading\" data-id=\"8b3229c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tracy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48e0316 elementor-widget elementor-widget-text-editor\" data-id=\"48e0316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Du lundi au vendredi, de 8 h 30 \u00e0 16 h.\u00a0 <\/strong><strong>(ferm\u00e9 le mercredi apr\u00e8s-midi)<\/strong><\/li><li><strong>Envoyez un <a href=\"mailto:tpresse@crcoc.ca\">courriel<\/a> ou appelez le <a href=\"tel:6138304357\">613-830-4357<\/a>, <\/strong><strong>\u00a0poste 151.<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1d095eb\" data-id=\"1d095eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bb09df elementor-widget elementor-widget-heading\" data-id=\"9bb09df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chlo\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcc792b elementor-widget elementor-widget-text-editor\" data-id=\"bcc792b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Du lundi au vendredi, de 8 h 30 \u00e0 16 h.\u00a0 <\/strong><strong>(ferm\u00e9 le mercredi apr\u00e8s-midi)<\/strong><\/li><li><strong>Envoyez un <a href=\"mailto:chloebl@crcoc.ca\">courriel<\/a> ou appelez le <a href=\"tel:6138304357\">613-830-4357<\/a>,<\/strong><strong> poste 154.<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-078e425 elementor-widget elementor-widget-heading\" data-id=\"078e425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FOIRES AUX QUESTIONS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6160a8 elementor-widget elementor-widget-toggle\" data-id=\"f6160a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2581\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2581\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">De quoi est-ce que je peux parler avec les intervenantes \u00e0 l\u2019accueil\u2009?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2581\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2581\"><p>N\u2019importe quoi. Aucun sujet n\u2019est interdit! Par exemple :<\/p><ul><li>Logement, emploi, 2SLGBTQIA+, alimentation, budget, ou encore ateliers qui vous int\u00e9ressent<\/li><li>Situation familiale qui vous stresse, une relation abusive, violence que vous subissez chez vous, ou n\u2019importe quelle inqui\u00e9tude sur l\u2019immigration ou votre sant\u00e9<\/li><li>La p\u00e9riode de d\u00e9prime que vous traversez, ou des pens\u00e9es suicidaires<\/li><li>Apr\u00e8s votre premi\u00e8re rencontre avec l\u2019intervenante, le CRCOC peut vous offrir du counselling<\/li><\/ul><p><b><i>Les <\/i><\/b>intervenantes vous \u00e9couteront toujours avec respect, empathie et attention. Elles auront toujours \u00e0 c\u0153ur de vous aider. C\u2019est pourquoi elles s\u2019assureront de prendre tout le temps qu\u2019il faut pour comprendre exactement votre situation. Ainsi, elles pourront identifier quelles sont les ressources dans la communaut\u00e9 qui vont le mieux r\u00e9pondre \u00e0 vos besoins.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2582\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2582\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qu\u2019est-ce qu\u2019une situation de crise pour le CRCOC\u2009?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2582\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2582\"><p>Une situation de crise, c\u2019est lorsque des circonstances ou une situation d\u00e9passent les capacit\u00e9s d\u2019une personne ou d\u2019une famille \u00e0 les r\u00e9soudre. Pour y arriver, cette personne ou cette famille a besoin d\u2019aide, il faut que quelqu\u2019un la guide. C\u2019est pourquoi le CRCOC joue un r\u00f4le tr\u00e8s important en temps de crise. Lorsqu\u2019une personne ou une famille s\u2019assoit avec une intervenante pour discuter d\u2019une situation, l\u2019intervenante les met \u00e0 l\u2019aise. Elle les \u00e9coute avec respect, attention et compassion. Elle prend tout le temps qu\u2019il faut pour bien comprendre la situation pour ensuite d\u00e9terminer quels sont les services qui vont vraiment aider cette personne ou cette famille.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2583\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2583\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qui peut rencontrer les intervenantes \u00e0 l\u2019accueil?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2583\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2583\"><p>D\u2019habitude, les intervenantes \u00e0 l\u2019accueil aident des personnes de plus de 16 ans. Mais des familles qui ont besoin d\u2019aide pour des personnes de moins de 16 ans peuvent aussi les rencontrer. Cela permet aux intervenantes de les diriger vers les services disponibles dans la communaut\u00e9 qui vont le mieux les aider. Quelques programmes du CRCOC exigent que les individus et les familles rencontrent tout d\u2019abord une intervenante \u00a0\u00e0 l\u2019accueil pour \u00e9valuer leur admissibilit\u00e9. S\u2019ils sont admissibles, l\u2019intervenante \u00a0recommande alors qu\u2019ils aient acc\u00e8s \u00e0 ces programmes.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2584\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2584\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel est le secteur couvert par CRCOC?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2584\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2584\"><p><span data-slate-object=\"text\" data-key=\"410\">Pour mieux vous aider, une intervenante \u00e0 l\u2019accueil d\u00e9termine dans quel secteur vous habitez bas\u00e9 sur votre code postal.<\/span> <strong>Nous desservons les codes postaux suivants\u00a0: K1E, K4A (r\u00e9gion d\u2019Orl\u00e9ans), K4B (Navan), K4C (Cumberland), et K0A (Vars et <span class=\"id_cf5d6f1c-4cb9-4524-b72c-ec1dc92f6050-61\" data-slate-object=\"mark\" data-info=\"noeud\">Sarsfield<\/span>).<\/strong> <span data-slate-object=\"text\" data-key=\"416\">Certains programmes, y compris la banque alimentaire, l\u2019imp\u00f4t sur le revenu et les fournitures scolaires, sont offerts seulement aux r\u00e9sidents d\u2019un secteur.<\/span> <span data-slate-object=\"text\" data-key=\"418\" data-slate-fragment=\"JTdCJTIyb2JqZWN0JTIyJTNBJTIyZG9jdW1lbnQlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJibG9jayUyMiUyQyUyMnR5cGUlMjIlM0ElMjJ6b25lJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiU3RCUyQyUyMm5vZGVzJTIyJTNBJTVCJTdCJTIyb2JqZWN0JTIyJTNBJTIyYmxvY2slMjIlMkMlMjJ0eXBlJTIyJTNBJTIybGlnbmUlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJibG9jayUyMiUyQyUyMnR5cGUlMjIlM0ElMjJkZWZhdWx0LWVsZW1lbnQlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJ0ZXh0JTIyJTJDJTIydGV4dCUyMiUzQSUyMlBvdXIlMjBtaWV1eCUyMHZvdXMlMjBhaWRlciUyQyUyMHVuZSUyMGludGVydmVuYW50ZSUyMCVDMyVBMCUyMGwlRTIlODAlOTlhY2N1ZWlsJTIwZCVDMyVBOXRlcm1pbmUlMjBkYW5zJTIwcXVlbCUyMHNlY3RldXIlMjB2b3VzJTIwaGFiaXRleiUyMGJhcyVDMyVBOSUyMHN1ciUyMHZvdHJlJTIwY29kZSUyMHBvc3RhbC4lMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU1RCU3RCUyQyU3QiUyMm9iamVjdCUyMiUzQSUyMnRleHQlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyJTIwJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJtYXJrJTIyJTJDJTIydHlwZSUyMiUzQSUyMnN0eWxlJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnN0eWxlJTIyJTNBJTIyQ2FyU2VwYXJhdGV1ciUyMiU3RCU3RCU1RCU3RCUyQyU3QiUyMm9iamVjdCUyMiUzQSUyMnRleHQlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyTm91cyUyMGRlc3NlcnZvbnMlMjBsZXMlMjBjb2RlcyUyMHBvc3RhdXglMjBzdWl2YW50cyVDMiVBMCUzQSUyMEsxRSUyQyUyMEs0QSUyMChyJUMzJUE5Z2lvbiUyMGQlRTIlODAlOTlPcmwlQzMlQTlhbnMpJTJDJTIwSzRCJTIwKE5hdmFuKSUyQyUyMEs0QyUyMChDdW1iZXJsYW5kKSUyQyUyMGV0JTIwSzBBJTIwKFZhcnMlMjBldCUyMCUyMiUyQyUyMm1hcmtzJTIyJTNBJTVCJTVEJTdEJTJDJTdCJTIyb2JqZWN0JTIyJTNBJTIydGV4dCUyMiUyQyUyMnRleHQlMjIlM0ElMjJTYXJzZmllbGQlMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU3QiUyMm9iamVjdCUyMiUzQSUyMm1hcmslMjIlMkMlMjJ0eXBlJTIyJTNBJTIyY2xhc3NOYW1lJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMmNsYXNzTmFtZSUyMiUzQSUyMmlkX2NmNWQ2ZjFjLTRjYjktNDUyNC1iNzJjLWVjMWRjOTJmNjA1MC02MSUyMiU3RCU3RCUyQyU3QiUyMm9iamVjdCUyMiUzQSUyMm1hcmslMjIlMkMlMjJ0eXBlJTIyJTNBJTIyc3R5bGUlMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTIyc3R5bGUlMjIlM0ElMjJUcmFpdEZpbk9yYW5nZSUyMiU3RCU3RCU1RCU3RCUyQyU3QiUyMm9iamVjdCUyMiUzQSUyMnRleHQlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyKS4lMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU1RCU3RCUyQyU3QiUyMm9iamVjdCUyMiUzQSUyMnRleHQlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyJTIwJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJtYXJrJTIyJTJDJTIydHlwZSUyMiUzQSUyMnN0eWxlJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnN0eWxlJTIyJTNBJTIyQ2FyU2VwYXJhdGV1ciUyMiU3RCU3RCU1RCU3RCUyQyU3QiUyMm9iamVjdCUyMiUzQSUyMnRleHQlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyQ2VydGFpbnMlMjBwcm9ncmFtbWVzJTJDJTIweSUyMGNvbXByaXMlMjBsYSUyMGJhbnF1ZSUyMGFsaW1lbnRhaXJlJTJDJTIwbCVFMiU4MCU5OWltcCVDMyVCNHQlMjBzdXIlMjBsZSUyMHJldmVudSUyMGV0JTIwbGVzJTIwZm91cm5pdHVyZXMlMjBzY29sYWlyZXMlMkMlMjBzb250JTIwb2ZmZXJ0cyUyMHNldWxlbWVudCUyMGF1eCUyMHIlQzMlQTlzaWRlbnRzJTIwZCVFMiU4MCU5OXVuJTIwc2VjdGV1ci4lMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU1RCU3RCUyQyU3QiUyMm9iamVjdCUyMiUzQSUyMnRleHQlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyJTIwJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlN0IlMjJvYmplY3QlMjIlM0ElMjJtYXJrJTIyJTJDJTIydHlwZSUyMiUzQSUyMnN0eWxlJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnN0eWxlJTIyJTNBJTIyQ2FyU2VwYXJhdGV1ciUyMiU3RCU3RCU1RCU3RCUyQyU3QiUyMm9iamVjdCUyMiUzQSUyMnRleHQlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyQ2VsYSUyMHBlcm1ldCUyMGRlJTIwciVDMyVBOXBvbmRyZSUyMGF1eCUyMGJlc29pbnMlMjBkZXMlMjBwZXJzb25uZXMlMjBkYW5zJTIwbGElMjBjb21tdW5hdXQlQzMlQTkuJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlNUQlN0QlNUQlN0QlNUQlN0QlNUQlN0QlNUQlN0Q=\">Cela permet de r\u00e9pondre aux besoins des personnes dans la communaut\u00e9.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2585\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2585\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel est le seuil de faible revenu pour le CRCOC? Est-ce que je dois avoir un faible revenu \u00eatre admissible aux services offerts?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2585\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2585\"><p>Le Centre de ressources communautaires Orl\u00e9ans-Cumberland \u00e9tablit l\u2019admissibilit\u00e9 \u00e0 faible revenu en se r\u00e9f\u00e9rant aux <a href=\"https:\/\/www.canada.ca\/fr\/emploi-developpement-social\/services\/travailleurs-etrangers\/fournisseurs-soins\/capacite-financiere.html\">Seuils de faible revenu (SFR)<\/a> publi\u00e9 chaque ann\u00e9e par Statistique Canada. L\u2019admissibilit\u00e9 \u00e0 certains programmes, tels que le Programme d\u2019effets scolaires, d\u00e9pend du revenu. Cependant, plusieurs autres programmes, y compris la banque alimentaire, le counselling, les r\u00e9f\u00e9rences et ON y va, sont accessibles sans \u00e9gard au revenu.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2586\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2586\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Est-ce que les intervenantes \u00e0 l\u2019accueil font partie de la Soci\u00e9t\u00e9 d\u2019aide \u00e0 l\u2019enfance (SAE) ou de Ontario au Travail?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2586\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2586\"><p>Non, les intervenantes \u00e0 l\u2019accueil du CRCOC ne font pas du tout partie de la Soci\u00e9t\u00e9 d\u2019aide \u00e0 l\u2019enfance ni de Ontario au travail.\u00a0 De plus, le milieu de travail des intervenantes est tout \u00e0 fait neutre, et sans parti pris ni pr\u00e9jug\u00e9. Dans ce lieu, les personnes se sentent \u00e0 l\u2019aise de parler de n\u2019importe quelle situation difficile qu\u2019elles vivent, de n\u2019importe quel d\u00e9fi auquel elles font face. Elles se sentent aussi tr\u00e8s libres d\u2019exprimer leur col\u00e8re, leurs frustrations, ou encore de discuter de leurs peurs, de leurs angoisses, et m\u00eame d\u2019une d\u00e9pression qu\u2019elles sont en train de vivre. Les intervenantes sont des personnes chaleureuses, humaines et pleines de compassion. Elles ont beaucoup d\u2019exp\u00e9rience de ce genre de situations dans la vie. C\u2019est pourquoi elles s\u2019assurent que les personnes qu\u2019elles rencontrent re\u00e7oivent l\u2019aide dont elles ont besoin. Elles travaillent avec les personnes qui viennent les voir et avec des partenaires dans la communaut\u00e9 pour r\u00e9soudre des situations conflictuelles. Elles d\u00e9fendent aussi les int\u00e9r\u00eats de ces personnes qui sont leurs clients et elles travaillent dans la communaut\u00e9 d\u2019Orl\u00e9ans-Cumberland.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2587\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2587\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mon m\u00e9decin me demande de rencontrer un psychiatre ou un psychologue pour discuter de mes probl\u00e8mes. Est-ce qu\u2019il y a un psychiatre ou un psychologue au CRCOC?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2587\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2587\"><p><span data-slate-object=\"text\" data-key=\"690\">Pour le moment, l\u2019\u00e9quipe <\/span><span data-slate-object=\"text\" data-key=\"691\"><span class=\"id_fac85dcb-4e8b-4f71-97f0-ba140cd8d20c-37\" data-slate-object=\"mark\" data-info=\"noeud\">du<\/span><\/span><span data-slate-object=\"text\" data-key=\"692\"> CRCOC ne comprend pas de psychiatre ni de psychologue.<\/span> <span data-slate-object=\"text\" data-key=\"642\">Cependant, les personnes qui font face \u00e0 des difficult\u00e9s peuvent consulter notre <a href=\"https:\/\/www.crcoc.ca\/fr\/adultes\/ressources-pour-adultes\/\">liste de ressources communautaires<\/a> (Soutien aux personnes et aux familles).<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-17bf231 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17bf231\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-80a5752\" data-id=\"80a5752\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf76c9f elementor-cta--skin-cover elementor-widget elementor-widget-call-to-action\" data-id=\"cf76c9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"http:\/\/crcoc.ca\/fr\/ressources-pour-adultes\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tRessources communautaires\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-53043f8\" data-id=\"53043f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe62704 elementor-cta--skin-cover elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"fe62704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.crcoc.ca\/fr\/adultes\/clinique-dimpot\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/02\/230210_IncomeTaxCLinicProgram_FR-1024x1024.png);\" role=\"img\" aria-label=\"230210_IncomeTaxCLinicProgram_FR\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tCliniques d'imp\u00f4ts\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ADULTES PROGRAMME D&rsquo;ACCUEIL Parlez-nous de votre visite Votre opinion compte. En cinq minutes, dites-nous comment on peut mieux r\u00e9pondre \u00e0 vos besoins. Cliquez ici Aucune donn\u00e9e ne servira \u00e0 vous identifier.Merci Le CRCOC est un endroit chaleureux qui accueille toute personne qui recherche du soutien et des ressources ou qui est confront\u00e9e \u00e0 une crise &#8230; <a title=\"Adultes\" class=\"read-more\" href=\"https:\/\/www.crcoc.ca\/fr\/adultes\/\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-684","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adultes - CRCOC - OCCRC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crcoc.ca\/fr\/adultes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adultes - CRCOC - OCCRC\" \/>\n<meta property=\"og:description\" content=\"ADULTES PROGRAMME D&rsquo;ACCUEIL Parlez-nous de votre visite Votre opinion compte. En cinq minutes, dites-nous comment on peut mieux r\u00e9pondre \u00e0 vos besoins. Cliquez ici Aucune donn\u00e9e ne servira \u00e0 vous identifier.Merci Le CRCOC est un endroit chaleureux qui accueille toute personne qui recherche du soutien et des ressources ou qui est confront\u00e9e \u00e0 une crise ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crcoc.ca\/fr\/adultes\/\" \/>\n<meta property=\"og:site_name\" content=\"CRCOC - OCCRC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OCCRC.CRCOC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T15:40:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-150x150.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OCCRC_CRCOC\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/adultes\\\/\",\"url\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/adultes\\\/\",\"name\":\"Adultes - CRCOC - OCCRC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/adultes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/adultes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.crcoc.ca\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Adults-150x150.png\",\"datePublished\":\"2019-02-01T22:11:27+00:00\",\"dateModified\":\"2026-05-11T15:40:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/adultes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/adultes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/adultes\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.crcoc.ca\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Adults-150x150.png\",\"contentUrl\":\"http:\\\/\\\/www.crcoc.ca\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Adults-150x150.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/adultes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adultes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/\",\"name\":\"CRCOC - OCCRC\",\"description\":\"Centre de ressources communautaires Orl\u00e9ans-Cumberland | Orl\u00e9ans-Cumberland Community Resource Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/#organization\",\"name\":\"Orl\u00e9ans-Cumberland Community Resource Centre\",\"url\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.crcoc.ca\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/cropped-Logo_OCCRCeachside-1.png\",\"contentUrl\":\"https:\\\/\\\/www.crcoc.ca\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/cropped-Logo_OCCRCeachside-1.png\",\"width\":512,\"height\":512,\"caption\":\"Orl\u00e9ans-Cumberland Community Resource Centre\"},\"image\":{\"@id\":\"https:\\\/\\\/www.crcoc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OCCRC.CRCOC\\\/\",\"https:\\\/\\\/x.com\\\/OCCRC_CRCOC\",\"https:\\\/\\\/instagram.com\\\/occrcyp_crcocpj\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adultes - CRCOC - OCCRC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crcoc.ca\/fr\/adultes\/","og_locale":"fr_FR","og_type":"article","og_title":"Adultes - CRCOC - OCCRC","og_description":"ADULTES PROGRAMME D&rsquo;ACCUEIL Parlez-nous de votre visite Votre opinion compte. En cinq minutes, dites-nous comment on peut mieux r\u00e9pondre \u00e0 vos besoins. Cliquez ici Aucune donn\u00e9e ne servira \u00e0 vous identifier.Merci Le CRCOC est un endroit chaleureux qui accueille toute personne qui recherche du soutien et des ressources ou qui est confront\u00e9e \u00e0 une crise ... Read more","og_url":"https:\/\/www.crcoc.ca\/fr\/adultes\/","og_site_name":"CRCOC - OCCRC","article_publisher":"https:\/\/www.facebook.com\/OCCRC.CRCOC\/","article_modified_time":"2026-05-11T15:40:32+00:00","og_image":[{"url":"http:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-150x150.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@OCCRC_CRCOC","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.crcoc.ca\/fr\/adultes\/","url":"https:\/\/www.crcoc.ca\/fr\/adultes\/","name":"Adultes - CRCOC - OCCRC","isPartOf":{"@id":"https:\/\/www.crcoc.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.crcoc.ca\/fr\/adultes\/#primaryimage"},"image":{"@id":"https:\/\/www.crcoc.ca\/fr\/adultes\/#primaryimage"},"thumbnailUrl":"http:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-150x150.png","datePublished":"2019-02-01T22:11:27+00:00","dateModified":"2026-05-11T15:40:32+00:00","breadcrumb":{"@id":"https:\/\/www.crcoc.ca\/fr\/adultes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.crcoc.ca\/fr\/adultes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.crcoc.ca\/fr\/adultes\/#primaryimage","url":"http:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-150x150.png","contentUrl":"http:\/\/www.crcoc.ca\/wp-content\/uploads\/2023\/01\/Adults-150x150.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.crcoc.ca\/fr\/adultes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.crcoc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Adultes"}]},{"@type":"WebSite","@id":"https:\/\/www.crcoc.ca\/fr\/#website","url":"https:\/\/www.crcoc.ca\/fr\/","name":"CRCOC - OCCRC","description":"Centre de ressources communautaires Orl\u00e9ans-Cumberland | Orl\u00e9ans-Cumberland Community Resource Center","publisher":{"@id":"https:\/\/www.crcoc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.crcoc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.crcoc.ca\/fr\/#organization","name":"Orl\u00e9ans-Cumberland Community Resource Centre","url":"https:\/\/www.crcoc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.crcoc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.crcoc.ca\/wp-content\/uploads\/2019\/01\/cropped-Logo_OCCRCeachside-1.png","contentUrl":"https:\/\/www.crcoc.ca\/wp-content\/uploads\/2019\/01\/cropped-Logo_OCCRCeachside-1.png","width":512,"height":512,"caption":"Orl\u00e9ans-Cumberland Community Resource Centre"},"image":{"@id":"https:\/\/www.crcoc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OCCRC.CRCOC\/","https:\/\/x.com\/OCCRC_CRCOC","https:\/\/instagram.com\/occrcyp_crcocpj\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.crcoc.ca\/fr\/wp-json\/wp\/v2\/pages\/684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crcoc.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.crcoc.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.crcoc.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crcoc.ca\/fr\/wp-json\/wp\/v2\/comments?post=684"}],"version-history":[{"count":164,"href":"https:\/\/www.crcoc.ca\/fr\/wp-json\/wp\/v2\/pages\/684\/revisions"}],"predecessor-version":[{"id":37670,"href":"https:\/\/www.crcoc.ca\/fr\/wp-json\/wp\/v2\/pages\/684\/revisions\/37670"}],"wp:attachment":[{"href":"https:\/\/www.crcoc.ca\/fr\/wp-json\/wp\/v2\/media?parent=684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}